{"id":115,"count":1,"description":"","link":"http:\/\/geuzenarchief.nl\/index.php\/tag\/revisie\/","name":"Revisie","slug":"revisie","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/geuzenarchief.nl\/index.php\/wp-json\/wp\/v2\/tags\/115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/geuzenarchief.nl\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/geuzenarchief.nl\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/geuzenarchief.nl\/index.php\/wp-json\/wp\/v2\/posts?tags=115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}